{"id":441,"count":2,"description":"","link":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/","name":"Internacional","slug":"internacional","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Internacional archivos - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Internacional archivos - OSEP Mendoza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/tag\\\/internacional\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/tag\\\/internacional\\\/\",\"name\":\"Internacional archivos - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/tag\\\/internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/tag\\\/internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Internacional archivos - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Internacional archivos - OSEP Mendoza","og_url":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/","og_site_name":"OSEP Mendoza","twitter_card":"summary_large_image","twitter_site":"@OsepMza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/","url":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/","name":"Internacional archivos - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/tag\/internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Internacional"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]}]}},"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts?tags=441"},{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/revista?tags=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}