{"id":53264,"date":"2024-05-17T22:52:16","date_gmt":"2024-05-18T01:52:16","guid":{"rendered":"https:\/\/osepmendoza.com.ar\/web\/?p=53264"},"modified":"2024-05-17T22:52:16","modified_gmt":"2024-05-18T01:52:16","slug":"autismo-contextos-amigables","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/","title":{"rendered":"Autismo: Contextos amigables"},"content":{"rendered":"<p><strong>En el marco de una organizaci\u00f3n conjunta, la Obra Social de los Empleados P\u00fablicos brind\u00f3 la charla <em>Autismo: Contextos amigables<\/em>. La jornada tuvo lugar en el Auditorio Papa Francisco del Parque Agnesi, San Mart\u00edn y cont\u00f3 con una gran concurrencia.<\/strong><\/p>\n<p>Alrededor de 400 personas se dieron cita al Centro de Congresos de General San Mart\u00edn, donde los profesionales de OSEP brindaron una charla para el acompa\u00f1ar el trastorno del espectro autista. La jornada fue organizada en conjunto a la Universidad Nacional de Cuyo, el Consejo Social y la Municipalidad de San Mart\u00edn.<\/p>\n<p>Se trata de un encuentro destinado a educadores, estudiantes, terapeutas y p\u00fablico en general quienes concurrieron en forma masiva a participar de las actividades. Los profesionales de OSEP fueron acompa\u00f1ados por el doctor Federico Cocconi, coordinador Asistencial de Zona Este y las referentes territoriales Anabel Mach\u00edn y Natalia \u00c9rcoli.<\/p>\n<p>Las disertaciones contaron con herramientas suficientes para brindar conocimientos nuevos y propiciar un enriquecedor debate junto a los presentes, generando un intercambio y di\u00e1logo permanente, aportando a una sociedad m\u00e1s comprensiva y preparada para acompa\u00f1ar a la diversidad de todas sus realidades.<\/p>\n<div id='gallery-1' class='gallery galleryid-53264 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo1\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo1.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo1-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo1-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo1-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo2.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo2-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo2-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo2-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo3\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo3.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo3-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo3-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo3-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo4\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo4.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo4-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo4-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo4-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo5\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo5.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo5-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo5-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo5-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo6\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo6.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo6-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo6-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo6-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo7\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo7.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo7-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo7-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo7-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismo8\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo8.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo8-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo8-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo8-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/autismoa\/'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismoa.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismoa.jpg 1920w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismoa-150x113.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismoa-768x576.jpg 768w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismoa-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>En el marco de una organizaci\u00f3n conjunta, la Obra Social&#8230;<\/p>\n","protected":false},"author":12,"featured_media":53265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[2066,2064,2065,230],"class_list":["post-53264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-amigables","tag-autismo","tag-contextos","tag-san-martin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autismo: Contextos amigables - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autismo: Contextos amigables - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"En el marco de una organizaci\u00f3n conjunta, la Obra Social...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-18T01:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastian Fernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastian Fernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/\"},\"author\":{\"name\":\"Sebastian Fernandez\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\"},\"headline\":\"Autismo: Contextos amigables\",\"datePublished\":\"2024-05-18T01:52:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/autismo0.jpg\",\"keywords\":[\"amigables\",\"autismo\",\"contextos\",\"san martin\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/\",\"name\":\"Autismo: Contextos amigables - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/autismo0.jpg\",\"datePublished\":\"2024-05-18T01:52:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/autismo0.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/autismo0.jpg\",\"width\":1200,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/autismo-contextos-amigables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autismo: Contextos amigables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\",\"name\":\"Sebastian Fernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"caption\":\"Sebastian Fernandez\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autismo: Contextos amigables - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/","og_locale":"es_ES","og_type":"article","og_title":"Autismo: Contextos amigables - OSEP Mendoza","og_description":"En el marco de una organizaci\u00f3n conjunta, la Obra Social...","og_url":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2024-05-18T01:52:16+00:00","og_image":[{"width":1200,"height":438,"url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg","type":"image\/jpeg"}],"author":"Sebastian Fernandez","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Sebastian Fernandez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/"},"author":{"name":"Sebastian Fernandez","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2"},"headline":"Autismo: Contextos amigables","datePublished":"2024-05-18T01:52:16+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/"},"wordCount":202,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#primaryimage"},"thumbnailUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg","keywords":["amigables","autismo","contextos","san martin"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/","url":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/","name":"Autismo: Contextos amigables - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#primaryimage"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#primaryimage"},"thumbnailUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg","datePublished":"2024-05-18T01:52:16+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#primaryimage","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2024\/05\/autismo0.jpg","width":1200,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/autismo-contextos-amigables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Autismo: Contextos amigables"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2","name":"Sebastian Fernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","caption":"Sebastian Fernandez"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/53264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=53264"}],"version-history":[{"count":1,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/53264\/revisions"}],"predecessor-version":[{"id":53275,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/53264\/revisions\/53275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media\/53265"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=53264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=53264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=53264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}