{"id":50693,"date":"2023-08-11T09:38:37","date_gmt":"2023-08-11T12:38:37","guid":{"rendered":"https:\/\/osepmendoza.com.ar\/web\/?p=50693"},"modified":"2023-08-30T13:57:53","modified_gmt":"2023-08-30T16:57:53","slug":"osep-realizara-su-xviii-jornada-de-enfermeria","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/","title":{"rendered":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda"},"content":{"rendered":"<p>El evento se llevar\u00e1 a cabo el jueves 31 de agosto, en el Auditorio Adolfo Calle. La inscripci\u00f3n es gratuita y con cupo limitado de 200 personas.<\/p>\n<p>Nuevamente la Obra Social de Empleados P\u00fablicos de Mendoza propone un espacio de actualizaci\u00f3n y debate para enfermeros y enfermeras. Esta edici\u00f3n contar\u00e1 con disertantes destacados del \u00e1mbito local y se centrar\u00e1 tanto en la atenci\u00f3n materno-neonatal como del adulto.<\/p>\n<p>Los profesionales de Enfermer\u00eda que se desempe\u00f1en en esas \u00e1reas y deseen participar, deben inscribirse a trav\u00e9s de Eventbrite en el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/www.eventbrite.com.ar\/e\/xviii-jornada-de-enfermeria-osep-tickets-676616798057?aff=oddtdtcreator\">https:\/\/www.eventbrite.com.ar\/e\/xviii-jornada-de-enfermeria-osep-tickets-676616798057?aff=oddtdtcreator<\/a><\/p>\n<p><strong>Programa\u21d3<\/strong><\/p>\n<p><a href=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/programa_enfermeria_30082023.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/programa_enfermeria_30082023.pdf<\/a><\/p>\n<p>Cabe aclarar que el encuentro se llevar\u00e1 a cabo en el Auditorio Adolfo Calle, Primitivo de la Reta 1042, de la Ciudad de Mendoza, su inscripci\u00f3n es gratuita y tiene un cupo limitado de 200 personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento se llevar\u00e1 a cabo el jueves 31 de&#8230;<\/p>\n","protected":false},"author":6,"featured_media":50708,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[],"class_list":["post-50693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"El evento se llevar\u00e1 a cabo el jueves 31 de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T12:38:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T16:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emiliano Sandobal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emiliano Sandobal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/\"},\"author\":{\"name\":\"Emiliano Sandobal\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/4e7a5e0118245838f9f783a763779211\"},\"headline\":\"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda\",\"datePublished\":\"2023-08-11T12:38:37+00:00\",\"dateModified\":\"2023-08-30T16:57:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/portada_j_enfermeria_11022023_2.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/\",\"name\":\"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/portada_j_enfermeria_11022023_2.jpeg\",\"datePublished\":\"2023-08-11T12:38:37+00:00\",\"dateModified\":\"2023-08-30T16:57:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/portada_j_enfermeria_11022023_2.jpeg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/portada_j_enfermeria_11022023_2.jpeg\",\"width\":1600,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-realizara-su-xviii-jornada-de-enfermeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/4e7a5e0118245838f9f783a763779211\",\"name\":\"Emiliano Sandobal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"caption\":\"Emiliano Sandobal\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/","og_locale":"es_ES","og_type":"article","og_title":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza","og_description":"El evento se llevar\u00e1 a cabo el jueves 31 de...","og_url":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2023-08-11T12:38:37+00:00","article_modified_time":"2023-08-30T16:57:53+00:00","og_image":[{"width":1600,"height":584,"url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg","type":"image\/jpeg"}],"author":"Emiliano Sandobal","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Emiliano Sandobal","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/"},"author":{"name":"Emiliano Sandobal","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/4e7a5e0118245838f9f783a763779211"},"headline":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda","datePublished":"2023-08-11T12:38:37+00:00","dateModified":"2023-08-30T16:57:53+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/"},"wordCount":159,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#primaryimage"},"thumbnailUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/","url":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/","name":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#primaryimage"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#primaryimage"},"thumbnailUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg","datePublished":"2023-08-11T12:38:37+00:00","dateModified":"2023-08-30T16:57:53+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#primaryimage","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/portada_j_enfermeria_11022023_2.jpeg","width":1600,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-realizara-su-xviii-jornada-de-enfermeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"OSEP realizar\u00e1 su XVIII Jornada de Enfermer\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/4e7a5e0118245838f9f783a763779211","name":"Emiliano Sandobal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","caption":"Emiliano Sandobal"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/50693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=50693"}],"version-history":[{"count":6,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/50693\/revisions"}],"predecessor-version":[{"id":51076,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/50693\/revisions\/51076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media\/50708"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=50693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=50693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=50693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}