{"id":39696,"date":"2019-10-25T15:59:34","date_gmt":"2019-10-25T18:59:34","guid":{"rendered":"https:\/\/osepmendoza.com.ar\/?p=39696"},"modified":"2019-10-25T15:59:34","modified_gmt":"2019-10-25T18:59:34","slug":"odontologos-de-osep-trabajan-por-la-prevencion","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/","title":{"rendered":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-39696 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-01\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-01-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-01-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-03\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-03-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-03-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-03-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-06\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-06-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-06-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-06-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-05\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-05-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-05-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-05-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-02\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-02-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-02-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-02-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-07\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-07-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-07-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-07-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/traumatismo-stand-08\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-08-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-08-150x150.jpg 150w, https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-08-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p align=\"left\"><strong>La Residencia en Odontolog\u00eda Preventiva y Social de OSEP concientiza a la comunidad sobre traumatismos dentales. Ayer realizaron charlas para docentes de una escuela de Puente de Hierro, hoy desarrollaron actividades abiertas al p\u00fablico en el Parque General San Mart\u00edn y ma\u00f1ana finalizan la campa\u00f1a con una jornada de capacitaci\u00f3n para odont\u00f3logos de la Obra Social y otras instituciones.<\/strong><\/p>\n<p align=\"left\">Profesionales del Centro Odontol\u00f3gico visitaron la Escuela Flavio Ferrari, de Puente de Hierro y realizaron exposiciones explicando cu\u00e1les son los tipos de traumatismo dentales, c\u00f3mo actuar y de qu\u00e9 forma evitar que se produzcan estas lesiones.<\/p>\n<p align=\"left\">Las charlas se destinaron a docentes debido a que las lesiones de los dientes y tejidos blandos, por una acci\u00f3n violenta en la cavidad bucal, son m\u00e1s frecuentes en ni\u00f1os y adolescentes. Los educadores pueden tener un rol muy importante ya que pueden asistir al lesionado r\u00e1pida y correctamente ayudando a mejorar el pron\u00f3stico del da\u00f1o.<\/p>\n<p align=\"left\">Los especialistas de OSEP expusieron no solo sobre las lesiones de piezas dentarias sino tambi\u00e9n de otras partes de la cavidad bucal tales como el labio y la lengua.<\/p>\n<p align=\"left\"><strong>Prevenci\u00f3n al aire libre<\/strong><\/p>\n<p align=\"left\">En el segundo d\u00eda de campa\u00f1a, los profesionales del Centro Odontol\u00f3gico, a trav\u00e9s del inflable con forma de Boca Gigante, folletos informativos y juegos, explicaron la importancia de conocer acerca de c\u00f3mo actuar y prevenir los traumatismos dentarios. Las actividades se llevaron a cabo en la Rotonda del Rosedal, del Parque General San Mart\u00edn.<\/p>\n<p align=\"left\">El espacio verde propici\u00f3 un lugar ideal para difundir la informaci\u00f3n preventiva ya que los traumatismos dentales se dan con mayor frecuencia en ni\u00f1os, adolescentes y deportistas.<\/p>\n<p align=\"left\">Se hizo hincapi\u00e9 en la importancia de actuar a tiempo, resaltando que el papel de la persona que est\u00e1 presente en el momento del accidente es fundamental para salvar la pieza dentaria.<\/p>\n<p align=\"left\">Personas de diferentes edades, familias y colegios se sumaron a la propuesta organizada por la Residencia en Odontolog\u00eda Preventiva y Social de OSEP.<\/p>\n<p align=\"left\">El objetivo es difundir qu\u00e9 hacer y c\u00f3mo prevenir las lesiones de los dientes y tejidos blandos que se producen por una acci\u00f3n violenta en la cavidad bucal. Estas situaciones se caracterizan por ser una experiencia traum\u00e1tica para el paciente y su familia debido a que en la mayor\u00eda de los casos afectan la est\u00e9tica y funci\u00f3n de los elementos dentarios, generando un gran impacto social y psicol\u00f3gico<\/p>\n<p align=\"left\">La Campa\u00f1a de Prevenci\u00f3n de Traumatismos Dentarios continuar\u00e1 ma\u00f1ana, 26 de octubre, con una jornada de capacitaci\u00f3n para profesionales de la Obra Social y otras instituciones, en el edificio Xeltahuina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Residencia en Odontolog\u00eda Preventiva y Social de OSEP concientiza&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[1360,265,1359,1109,1193,110,112,113,360,1358],"class_list":["post-39696","post","type-post","status-publish","format-gallery","hentry","category-noticias","tag-boca","tag-centro-odontologico","tag-dentales","tag-dientes","tag-gigante","tag-odontologia","tag-osep","tag-prevencion","tag-residencia","tag-traumatismos","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"La Residencia en Odontolog\u00eda Preventiva y Social de OSEP concientiza...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-25T18:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-01-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Emiliano Sandobal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emiliano Sandobal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/\"},\"author\":{\"name\":\"Emiliano Sandobal\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/4e7a5e0118245838f9f783a763779211\"},\"headline\":\"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n\",\"datePublished\":\"2019-10-25T18:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/\"},\"wordCount\":466,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"keywords\":[\"Boca\",\"Centro Odontol\u00f3gico\",\"Dentales\",\"dientes\",\"gigante\",\"odontologia\",\"osep\",\"prevenci\u00f3n\",\"residencia\",\"Traumatismos\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/\",\"name\":\"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"datePublished\":\"2019-10-25T18:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/odontologos-de-osep-trabajan-por-la-prevencion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/4e7a5e0118245838f9f783a763779211\",\"name\":\"Emiliano Sandobal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g\",\"caption\":\"Emiliano Sandobal\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/","og_locale":"es_ES","og_type":"article","og_title":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza","og_description":"La Residencia en Odontolog\u00eda Preventiva y Social de OSEP concientiza...","og_url":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2019-10-25T18:59:34+00:00","og_image":[{"url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2019\/10\/traumatismo-stand-01-150x150.jpg","type":"","width":"","height":""}],"author":"Emiliano Sandobal","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Emiliano Sandobal","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/"},"author":{"name":"Emiliano Sandobal","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/4e7a5e0118245838f9f783a763779211"},"headline":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n","datePublished":"2019-10-25T18:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/"},"wordCount":466,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"keywords":["Boca","Centro Odontol\u00f3gico","Dentales","dientes","gigante","odontologia","osep","prevenci\u00f3n","residencia","Traumatismos"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/","url":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/","name":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"datePublished":"2019-10-25T18:59:34+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/odontologos-de-osep-trabajan-por-la-prevencion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Odont\u00f3logos de OSEP trabajan por la prevenci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/4e7a5e0118245838f9f783a763779211","name":"Emiliano Sandobal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3b22a03e2853d7165313b51b54fbd33fb530becf0ffe6a70f96b195ca724512?s=96&d=mm&r=g","caption":"Emiliano Sandobal"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/39696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=39696"}],"version-history":[{"count":4,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/39696\/revisions"}],"predecessor-version":[{"id":39715,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/39696\/revisions\/39715"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=39696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=39696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=39696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}