{"id":33318,"date":"2018-07-31T15:13:10","date_gmt":"2018-07-31T15:13:10","guid":{"rendered":"http:\/\/osepmendoza.com.ar\/web\/?p=33318"},"modified":"2018-12-17T11:50:49","modified_gmt":"2018-12-17T14:50:49","slug":"cocina-sin-tacc-junto-a-maria-urrutigoity","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/","title":{"rendered":"Cocina sin TACC junto a Mar\u00eda Urrutigoity"},"content":{"rendered":"<p class=\"western\"><strong><span style=\"font-family: Arial,sans-serif;\">Gran inter\u00e9s y concurrencia en el segundo Taller de Cocina Saludable. La prestigiosa cocinera mendocina elabor\u00f3 recetas apta para cel\u00edacos. El encuentro tuvo lugar en el sal\u00f3n vidriado de OSEP y cont\u00f3 con la presencia la licenciada Soledad Ciurletti, coordinadora del Programa Ser Cel\u00edaco de OSEP.<br \/>\n<\/span><\/strong><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">El Departamento de Nutrici\u00f3n y el Programa Ser Cel\u00edaco de OSEP ofrecieron un nuevo Taller de Cocina Saludable con la participaci\u00f3n <strong>Mar\u00eda Urrutigoity<\/strong>, quien ofreci\u00f3 recetas libres de gluten.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Se trata de una propuesta que se realiza mes a mes y tiene como objetivo ense\u00f1ar a cocinar recetas saludables, f\u00e1ciles y con productos de estaci\u00f3n para toda la familia.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: arial,sans-serif;\">En esta oportunidad <\/span><span style=\"font-family: arial,sans-serif;\">el encuentro fue pensado<\/span><span style=\"font-family: arial,sans-serif;\"> para las personas con celiaqu\u00ed<\/span><span style=\"font-family: arial,sans-serif;\">a y la dificultad que a veces se presenta de cocinar en casa y al mismo tiempo ahorrar en la compra de los productos sin TACC. <\/span><span style=\"font-family: Arial,sans-serif;\">El evento cont\u00f3 con gran concurrencia y tuvo lugar en el Sal\u00f3n Vidriado de la Obra Social, en Salta y Vicente L\u00f3pez, de Ciudad<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: arial,sans-serif;\">M\u00e1s de 100 personas estuvieron atentas a las recetas que present\u00f3 Mar\u00eda. La primera fue la preparaci\u00f3n de la masa base para empanadas y tartas libres del gluten y, posteriormente, la elaboraci\u00f3n de una pizza de r\u00facula con parmesano y tomates cherry.\u00a0 <\/span><\/p>\n<p class=\"western\"><span style=\"font-family: arial,sans-serif;\">En constante interacci\u00f3n con el p\u00fablico, <\/span><span style=\"font-family: arial,sans-serif;\">la cocinera<\/span><span style=\"font-family: arial,sans-serif;\"> aport\u00f3 varios tips para tener una masa ideal para estas comidas y poder brindar calidad y facilidad a la hora de cocinar. Por su parte la licenciada Soledad Ciurletti, coordinadora del programa, escuch\u00f3 atentamente a los participantes y respondi\u00f3 a cada una de sus consultas tanto de pacientes como de p\u00fablico general. Los presentes tuvieron la oportunidad de consultar por productos espec\u00edficos que se ofrecen en el mercado, experimentar las texturas de las elaboraciones y finalmente degustar las preparaciones.<\/span><\/p>\n<p class=\"western\">Se estima que fines de agosto Mar\u00eda Urrutigoity volver\u00e1 a presentar un nuevo taller en el marco de una alimentaci\u00f3n saludable.<\/p>\n<p class=\"western\">\n<p class=\"western\"><a href=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33339 alignnone\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png\" alt=\"masa sin tacc twit_Mesa de trabajo 1\" width=\"680\" height=\"341\" \/><\/a>\u00a0 <a href=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-elab-twit_Mesa-de-trabajo-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33340 alignnone\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-elab-twit_Mesa-de-trabajo-1.png\" alt=\"masa elab twit_Mesa de trabajo 1\" width=\"680\" height=\"341\" \/><\/a><a href=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/pizza-ingr-twit_Mesa-de-trabajo-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33341 alignnone\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/pizza-ingr-twit_Mesa-de-trabajo-1.png\" alt=\"pizza ingr twit_Mesa de trabajo 1\" width=\"680\" height=\"341\" \/><\/a> <a href=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/pizza-elab-twit_Mesa-de-trabajo-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33342 alignnone\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/pizza-elab-twit_Mesa-de-trabajo-1.png\" alt=\"pizza elab twit_Mesa de trabajo 1\" width=\"680\" height=\"340\" \/><\/a><\/p>\n<p class=\"western\">\n","protected":false},"excerpt":{"rendered":"<p>Gran inter\u00e9s y concurrencia en el segundo Taller de Cocina&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[979,980,108,983,145],"class_list":["post-33318","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-cocina","tag-maria-urrutigoity","tag-ser-celiaco","tag-sin-tacc","tag-taller"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"Gran inter\u00e9s y concurrencia en el segundo Taller de Cocina...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-31T15:13:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-17T14:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png\" \/>\n<meta name=\"author\" content=\"Sebastian Fernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastian Fernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/\"},\"author\":{\"name\":\"Sebastian Fernandez\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\"},\"headline\":\"Cocina sin TACC junto a Mar\u00eda Urrutigoity\",\"datePublished\":\"2018-07-31T15:13:10+00:00\",\"dateModified\":\"2018-12-17T14:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/\"},\"wordCount\":348,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/masa-ingr-twit_Mesa-de-trabajo-1.png\",\"keywords\":[\"cocina\",\"Mar\u00eda Urrutigoity\",\"ser cel\u00edaco\",\"Sin TACC\",\"taller\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/\",\"name\":\"Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/masa-ingr-twit_Mesa-de-trabajo-1.png\",\"datePublished\":\"2018-07-31T15:13:10+00:00\",\"dateModified\":\"2018-12-17T14:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#primaryimage\",\"url\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/masa-ingr-twit_Mesa-de-trabajo-1.png\",\"contentUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/masa-ingr-twit_Mesa-de-trabajo-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/cocina-sin-tacc-junto-a-maria-urrutigoity\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocina sin TACC junto a Mar\u00eda Urrutigoity\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\",\"name\":\"Sebastian Fernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"caption\":\"Sebastian Fernandez\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/","og_locale":"es_ES","og_type":"article","og_title":"Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza","og_description":"Gran inter\u00e9s y concurrencia en el segundo Taller de Cocina...","og_url":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2018-07-31T15:13:10+00:00","article_modified_time":"2018-12-17T14:50:49+00:00","og_image":[{"url":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png","type":"","width":"","height":""}],"author":"Sebastian Fernandez","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Sebastian Fernandez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/"},"author":{"name":"Sebastian Fernandez","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2"},"headline":"Cocina sin TACC junto a Mar\u00eda Urrutigoity","datePublished":"2018-07-31T15:13:10+00:00","dateModified":"2018-12-17T14:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/"},"wordCount":348,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#primaryimage"},"thumbnailUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png","keywords":["cocina","Mar\u00eda Urrutigoity","ser cel\u00edaco","Sin TACC","taller"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/","url":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/","name":"Cocina sin TACC junto a Mar\u00eda Urrutigoity - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#primaryimage"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#primaryimage"},"thumbnailUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png","datePublished":"2018-07-31T15:13:10+00:00","dateModified":"2018-12-17T14:50:49+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#primaryimage","url":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png","contentUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2018\/07\/masa-ingr-twit_Mesa-de-trabajo-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/cocina-sin-tacc-junto-a-maria-urrutigoity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Cocina sin TACC junto a Mar\u00eda Urrutigoity"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2","name":"Sebastian Fernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","caption":"Sebastian Fernandez"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/33318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=33318"}],"version-history":[{"count":1,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/33318\/revisions"}],"predecessor-version":[{"id":35441,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/33318\/revisions\/35441"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=33318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=33318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=33318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}