{"id":31356,"date":"2018-01-03T18:21:07","date_gmt":"2018-01-03T18:21:07","guid":{"rendered":"http:\/\/osepmendoza.com.ar\/web\/?p=31356"},"modified":"2018-12-17T11:51:30","modified_gmt":"2018-12-17T14:51:30","slug":"actividades-para-embarazadas-en-osep","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/","title":{"rendered":"Actividades para embarazadas en OSEP"},"content":{"rendered":"<p class=\"western\"><strong><span style=\"font-family: Arial,sans-serif;\">Como las actividades del Taller de Preparaci\u00f3n Integral para la Maternidad de OSEP contin\u00faan durante el verano, sin receso, haremos un repaso de las jornadas que se llevan a cabo.<\/span><\/strong><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Se trata de 5 encuentros, de dos horas cada uno, destinados a las futuras mam\u00e1s. No importa en qu\u00e9 encuentro comiencen, lo importante es que completen los talleres.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Durante la primera hora se exponen contenidos te\u00f3ricos y durante la segunda se desarrolla actividad f\u00edsica. <\/span><span style=\"font-family: Arial,sans-serif;\">Los encuentros se realizan en el SUM I del edificio Xeltahuina y est\u00e1n a cargo de un equipo interdisciplinario de profesionales.<\/span><\/p>\n<p class=\"western\"><strong><span style=\"font-family: Arial,sans-serif;\">Los Talleres<\/span><\/strong><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">&#8211; Mitos del embarazo. Preparto y trabajo de parto<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">&#8211; Puerperio. Anticoncepci\u00f3n<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">&#8211; Lactancia. Mitos. Posiciones para amamantar. Conservaci\u00f3n de la leche<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">&#8211; Taller de Crianza (durante ese d\u00eda no hay actividad f\u00edsica)<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">&#8211; Primeros cuidados del beb\u00e9. Prevenci\u00f3n de accidentes<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">En el caso de las mayores de 19 a\u00f1os, las clases que se dictan los mi\u00e9rcoles, de 11 a 13 o los jueves, de 18 a 20, en el SUM I del edificio Xeltahuina, Salta 877, Ciudad. All\u00ed un grupo de profesionales, conformado por enfermeros, licenciadas en Obstetricia, profesores de Educaci\u00f3n F\u00edsica, kinesi\u00f3logos y m\u00e9dicos, lleva adelante cada jornada.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Por su parte, las futuras mam\u00e1s menores de 19 pueden acceder a los encuentros de preparaci\u00f3n que realiza el Programa Adolescencia, los martes, de 10.30 a 12.30 o de 18 a 20, en el SUM II del mismo edificio.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Las interesadas en participar podr\u00e1n hacerlo solicitando turno al 0810 810 1033 opci\u00f3n 7, de 14 a 20. Tambi\u00e9n se podr\u00e1n incorporar por demanda espont\u00e1nea.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como las actividades del Taller de Preparaci\u00f3n Integral para la&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[402,153,695,404],"class_list":["post-31356","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-curso","tag-embarazo","tag-preparacion-integral-para-la-maternidad","tag-preparto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actividades para embarazadas en OSEP - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actividades para embarazadas en OSEP - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"Como las actividades del Taller de Preparaci\u00f3n Integral para la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-03T18:21:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-17T14:51:30+00:00\" \/>\n<meta name=\"author\" content=\"Sebastian Fernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastian Fernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/\"},\"author\":{\"name\":\"Sebastian Fernandez\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\"},\"headline\":\"Actividades para embarazadas en OSEP\",\"datePublished\":\"2018-01-03T18:21:07+00:00\",\"dateModified\":\"2018-12-17T14:51:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"keywords\":[\"curso\",\"embarazo\",\"preparaci\u00f3n integral para la maternidad\",\"preparto\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/\",\"name\":\"Actividades para embarazadas en OSEP - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"datePublished\":\"2018-01-03T18:21:07+00:00\",\"dateModified\":\"2018-12-17T14:51:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/actividades-para-embarazadas-en-osep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actividades para embarazadas en OSEP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\",\"name\":\"Sebastian Fernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"caption\":\"Sebastian Fernandez\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actividades para embarazadas en OSEP - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/","og_locale":"es_ES","og_type":"article","og_title":"Actividades para embarazadas en OSEP - OSEP Mendoza","og_description":"Como las actividades del Taller de Preparaci\u00f3n Integral para la...","og_url":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2018-01-03T18:21:07+00:00","article_modified_time":"2018-12-17T14:51:30+00:00","author":"Sebastian Fernandez","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Sebastian Fernandez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/"},"author":{"name":"Sebastian Fernandez","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2"},"headline":"Actividades para embarazadas en OSEP","datePublished":"2018-01-03T18:21:07+00:00","dateModified":"2018-12-17T14:51:30+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/"},"wordCount":272,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"keywords":["curso","embarazo","preparaci\u00f3n integral para la maternidad","preparto"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/","url":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/","name":"Actividades para embarazadas en OSEP - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"datePublished":"2018-01-03T18:21:07+00:00","dateModified":"2018-12-17T14:51:30+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/actividades-para-embarazadas-en-osep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Actividades para embarazadas en OSEP"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2","name":"Sebastian Fernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","caption":"Sebastian Fernandez"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/31356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=31356"}],"version-history":[{"count":1,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/31356\/revisions"}],"predecessor-version":[{"id":35583,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/31356\/revisions\/35583"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=31356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=31356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=31356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}