{"id":29119,"date":"2017-07-05T17:38:02","date_gmt":"2017-07-05T17:38:02","guid":{"rendered":"http:\/\/osepmendoza.com.ar\/web\/?p=29119"},"modified":"2018-12-17T11:52:03","modified_gmt":"2018-12-17T14:52:03","slug":"osep-te-invita-a-festejar-la-independencia","status":"publish","type":"post","link":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/","title":{"rendered":"OSEP te invita a festejar la Independencia"},"content":{"rendered":"<p class=\"western\"><strong><span style=\"font-family: Arial,sans-serif;\">Como parte de las actividades por el D\u00eda de la Independencia, declarada el 9 de julio de 1816, la Obra Social de Empleados P\u00fablicos realizar\u00e1 un acto para sus afiliados.<\/span><\/strong><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Del encuentro, que tendr\u00e1 lugar ma\u00f1ana (jueves 6\/7), a las 10, en el sal\u00f3n vidriado, ubicado en Salta y Vicente L\u00f3pez, frente al edificio Xeltahuina, participar\u00e1n autoridades, trabajadores y afiliados de OSEP.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Por su parte la Direcci\u00f3n de Atenci\u00f3n Primaria, a trav\u00e9s de los programas Salud + Recreaci\u00f3n y Gesti\u00f3n Cl\u00ednica para Pacientes Cr\u00f3nicos, pondr\u00e1 en escena un n\u00famero folcl\u00f3rico a cargo de sus profesores y pacientes para cerrar una ma\u00f1ana festiva, compartiendo m\u00fasica y chocolate.<\/span><\/p>\n<p class=\"western\"><strong><span style=\"font-family: Arial,sans-serif;\">201 a\u00f1os de Independencia<\/span><\/strong><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">El 9 de julio de 1816, en la hist\u00f3rica Casa de Tucum\u00e1n y con la presencia de diputados de casi todo el territorio, se aprob\u00f3 y firm\u00f3 la Declaraci\u00f3n de la Independencia de las Provincias Unidas del Sur. Aunque durante los d\u00edas posteriores se continu\u00f3 discutiendo la forma de gobierno, tambi\u00e9n se oficializ\u00f3 nuestra bandera, creada cuatro a\u00f1os antes por Belgrano, dando forma a nuestro propio destino.<\/span><\/p>\n<p class=\"western\"><span style=\"font-family: Arial,sans-serif;\">Con aciertos, errores, defectos y virtudes han pasado 201 a\u00f1os de este hecho tan importante que ser\u00e1 celebrado en OSEP por sus distintos actores. As\u00ed autoridades, trabajadores y afiliados compartir\u00e1n este encuentro con colores celeste y blanco.<\/span><\/p>\n<p class=\"western\"><a href=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29120\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png\" alt=\"invitacion 9 de julio-01\" width=\"600\" height=\"400\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades por el D\u00eda de la&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[101],"tags":[309,363,513,172],"class_list":["post-29119","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-acto","tag-cronicos","tag-independencia","tag-salud-recreacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OSEP te invita a festejar la Independencia - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OSEP te invita a festejar la Independencia - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"Como parte de las actividades por el D\u00eda de la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-05T17:38:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-17T14:52:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png\" \/>\n<meta name=\"author\" content=\"Sebastian Fernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastian Fernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/\"},\"author\":{\"name\":\"Sebastian Fernandez\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\"},\"headline\":\"OSEP te invita a festejar la Independencia\",\"datePublished\":\"2017-07-05T17:38:02+00:00\",\"dateModified\":\"2018-12-17T14:52:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/invitacion-9-de-julio-01.png\",\"keywords\":[\"acto\",\"cr\u00f3nicos\",\"Independencia\",\"Salud + Recreaci\u00f3n\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/\",\"name\":\"OSEP te invita a festejar la Independencia - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/invitacion-9-de-julio-01.png\",\"datePublished\":\"2017-07-05T17:38:02+00:00\",\"dateModified\":\"2018-12-17T14:52:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/invitacion-9-de-julio-01.png\",\"contentUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/invitacion-9-de-julio-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/osep-te-invita-a-festejar-la-independencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OSEP te invita a festejar la Independencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/90986df7128a51e32bb66102fc247eb2\",\"name\":\"Sebastian Fernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g\",\"caption\":\"Sebastian Fernandez\"},\"sameAs\":[\"http:\\\/\\\/osepmendoza.com.ar\\\/web\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OSEP te invita a festejar la Independencia - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/","og_locale":"es_ES","og_type":"article","og_title":"OSEP te invita a festejar la Independencia - OSEP Mendoza","og_description":"Como parte de las actividades por el D\u00eda de la...","og_url":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_published_time":"2017-07-05T17:38:02+00:00","article_modified_time":"2018-12-17T14:52:03+00:00","og_image":[{"url":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png","type":"","width":"","height":""}],"author":"Sebastian Fernandez","twitter_card":"summary_large_image","twitter_creator":"@OsepMza","twitter_site":"@OsepMza","twitter_misc":{"Escrito por":"Sebastian Fernandez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#article","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/"},"author":{"name":"Sebastian Fernandez","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2"},"headline":"OSEP te invita a festejar la Independencia","datePublished":"2017-07-05T17:38:02+00:00","dateModified":"2018-12-17T14:52:03+00:00","mainEntityOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/"},"wordCount":238,"publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#primaryimage"},"thumbnailUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png","keywords":["acto","cr\u00f3nicos","Independencia","Salud + Recreaci\u00f3n"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/","url":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/","name":"OSEP te invita a festejar la Independencia - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#primaryimage"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#primaryimage"},"thumbnailUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png","datePublished":"2017-07-05T17:38:02+00:00","dateModified":"2018-12-17T14:52:03+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#primaryimage","url":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png","contentUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2017\/07\/invitacion-9-de-julio-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/osep-te-invita-a-festejar-la-independencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"OSEP te invita a festejar la Independencia"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]},{"@type":"Person","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/person\/90986df7128a51e32bb66102fc247eb2","name":"Sebastian Fernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc42d53caabe846896e06ed8955a60e82b2b829babcb731f86f26c42378bcfec?s=96&d=mm&r=g","caption":"Sebastian Fernandez"},"sameAs":["http:\/\/osepmendoza.com.ar\/web"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/29119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=29119"}],"version-history":[{"count":1,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/29119\/revisions"}],"predecessor-version":[{"id":35772,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/posts\/29119\/revisions\/35772"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=29119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/categories?post=29119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/tags?post=29119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}