{"id":1253,"date":"2020-05-19T19:20:30","date_gmt":"2020-05-19T19:20:30","guid":{"rendered":"http:\/\/34.67.86.69\/?page_id=1253"},"modified":"2022-08-29T11:24:26","modified_gmt":"2022-08-29T14:24:26","slug":"proveedores-2","status":"publish","type":"page","link":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/","title":{"rendered":"Proveedores"},"content":{"rendered":"<section class=\"sh-section sh-section-827082db83664970c10192a21ca3210b fw-main-row sh-section-visibility-everywhere\">\r\n\t\r\n\t\r\n\t<div class=\"sh-section-container container\">\r\n\t\t\t<\/div>\r\n<\/section>\r\n\r\n<section class=\"sh-section sh-section-3ada0692a6cad8c9d8ce792998bcaff7 fw-main-row servicioss sh-section-visibility-everywhere\" id=\"col-accesos\">\r\n\t\r\n\t\r\n\t<div class=\"sh-section-container container\">\r\n\t\t<div class=\"fw-row\">\n\t\r\n<div class=\"sh-column sh-column-107674e4341b6c4d4a45669c0eaec7ba fw-col-xs-12\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\r\n<div id=\"text-block-28191f6aa4b2ca62c7247161ad89a6ec\" class=\"sh-text-block\">\r\n\t<h2 style=\"margin-bottom: 15px; text-align: center;\"><span style=\"color: #746e80; font-size: 30px;\">Proveedores de OSEP<\/span><\/h2><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n<\/div>\n\n<div class=\"fw-row\">\n\t\r\n<div class=\"sh-column sh-column-ea844887c632afe063a698888ac93272 fw-col-xs-12\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\r\n<div id=\"divider-7a5f46966b04368fcd40172e8b18855d\" class=\"sh-divider sh-divider-center sh-divider-content-none\">\r\n\t\t\t<div class=\"sh-divider-line\"><\/div>\r\n\t<\/div>\r\n\r\n<div class=\"sh-empty-space\" id=\"empty-space-f6c89df7bb11ecfca42ca5988d234ea3\"><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n<\/div>\n\n<div class=\"fw-row\">\n\t\r\n<div class=\"sh-column sh-column-23a4cac523c6d56c7d628c91dfdcf545 fw-col-xs-12 fw-col-sm-3\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-f04905f939195174a7c7c475a7182f48 fw-col-xs-12 fw-col-sm-15 accic sh-column-mobile-padding\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t<div class=\"sh-output-html\">\r\n\t<a href=\"https:\/\/www.osep.mendoza.gov.ar\/webapp_pri\/action\/index\" target=\"_blank\"><div class=\"box-acceso\">\n<img decoding=\"async\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg\" alt=\"icono SISAO\"\/>\n<h4>Ingreso SISAO<\/h4>\n<\/div><\/a><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-2431426758fb9e4307371b1e3bbc2439 fw-col-xs-12 fw-col-sm-15 accic sh-column-mobile-padding\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t<div class=\"sh-output-html\">\r\n\t<a href=\"https:\/\/comprarosep.mendoza.gov.ar\/\" target=\"_blank\"><div class=\"box-acceso\">\n<img decoding=\"async\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/comprar.svg\" alt=\"icono Planes Especiales\"\/>\n<h4>Ingreso a COMPR.AR<\/h4>\n<\/div><\/a><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-5c0a4d5323a7b807a4aa8adf9a590731 fw-col-xs-12 fw-col-sm-3\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n<\/div>\n\n<div class=\"fw-row\">\n\t\r\n<div class=\"sh-column sh-column-b634577861b8bd82d01fabf65f2d122e fw-col-xs-12 fw-col-sm-3\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-db921fcd88804ccd3f02a36a90fd65c3 fw-col-xs-12 fw-col-sm-15 accic\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t<div class=\"sh-output-html\">\r\n\t<a href=\"https:\/\/osepmendoza.com.ar\/web\/inicio-expediente-facturacion\/\"><div class=\"box-acceso\">\n<img decoding=\"async\" src=\"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/boton-whats-app.png\" alt=\"icono salud ocupacional\"\/>\n<h4>Inicio Expediente Facturaci\u00f3n<\/h4>\n<\/div><\/a><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-1b3011aed6bf8090a6e5c1c5127cabc7 fw-col-xs-12 fw-col-sm-15 accic\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t<div class=\"sh-output-html\">\r\n\t<a href=\"https:\/\/osepmendoza.com.ar\/web\/tramites-y-consultas-2\/seguimiento-de-expedientes\/\"><div class=\"box-acceso\">\n<img decoding=\"async\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/seguimiento-expediente.svg\" alt=\"icono salud ocupacional\"\/>\n<h4>Seguimiento de Expediente<\/h4>\n<\/div><\/a><\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n\r\n<div class=\"sh-column sh-column-a61de4f4b8aa44da3923044e73f0d5d3 fw-col-xs-12 fw-col-sm-3\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n<\/div>\n\n\t<\/div>\r\n<\/section>\r\n\r\n<section class=\"sh-section sh-section-11952b1bf63d0bb8f5d9c8c07533feb1 fw-main-row sh-section-visibility-everywhere\">\r\n\t\r\n\t\r\n\t<div class=\"sh-section-container container\">\r\n\t\t<div class=\"fw-row\">\n\t\r\n<div class=\"sh-column sh-column-2be6ee00392a834d777996ec3a118ea4 fw-col-xs-12 news\" >\r\n\r\n\t\r\n\t<div class=\"sh-column-wrapper\">\r\n\t\t\r\n<div id=\"text-block-bfba8583eadd64474dcfbcb52281ea4c\" class=\"sh-text-block\">\r\n\t<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-429 aligncenter\" src=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/helposep.svg\" alt=\"ayuda\" width=\"84\" height=\"102\" \/><\/p><h2 style=\"text-align: center;\">\u00bfNecesit\u00e1s m\u00e1s ayuda?<\/h2><p style=\"text-align: center;\"><span style=\"font-size: 18px;\">Visit\u00e1 nuestra secci\u00f3n de ayuda, preguntas frecuentes y tutoriales.<\/span><\/p><\/div>\r\n\r\n<div id=\"button-c9aa4240d46fa009c60ba4a9e9074d4a\" class=\"sh-button-container  sh-button-style-1\">\r\n\t<div class=\"sh-element-margin\">\r\n\t\t<a href=\"https:\/\/osepmendoza.com.ar\/ayuda\" target=\"_blank\" class=\"sh-button sh-button-medium \">\r\n\r\n\t\t\t\r\n\t\t\t\t\t\t\t<span class=\"sh-button-text\">\r\n\t\t\t\t\tM\u00e1s ayuda\t\t\t\t<\/span>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/a>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\t<\/div>\r\n\r\n\r\n\t\t\r\n\r\n<\/div>\r\n<\/div>\n\n\t<\/div>\r\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Proveedores de OSEP Ingreso SISAO Ingreso a COMPR.AR Inicio Expediente&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":44,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-1253","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proveedores - OSEP Mendoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proveedores - OSEP Mendoza\" \/>\n<meta property=\"og:description\" content=\"Proveedores de OSEP Ingreso SISAO Ingreso a COMPR.AR Inicio Expediente...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/\" \/>\n<meta property=\"og:site_name\" content=\"OSEP Mendoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSEP.MendozaArg\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-29T14:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OsepMza\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/\",\"name\":\"Proveedores - OSEP Mendoza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/proveedor.svg\",\"datePublished\":\"2020-05-19T19:20:30+00:00\",\"dateModified\":\"2022-08-29T14:24:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/proveedor.svg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/proveedor.svg\",\"width\":66,\"height\":43},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/proveedores-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proveedores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"name\":\"OSEP Mendoza\",\"description\":\"Obra Social de los Empleados P\u00fablicos de Mendoza\",\"publisher\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#organization\",\"name\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"contentUrl\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lkTM9T9z.jpg\",\"width\":334,\"height\":334,\"caption\":\"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza\"},\"image\":{\"@id\":\"https:\\\/\\\/osepmendoza.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSEP.MendozaArg\\\/\",\"https:\\\/\\\/x.com\\\/OsepMza\",\"https:\\\/\\\/www.instagram.com\\\/osep.mendoza\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/osepvideos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proveedores - OSEP Mendoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/","og_locale":"es_ES","og_type":"article","og_title":"Proveedores - OSEP Mendoza","og_description":"Proveedores de OSEP Ingreso SISAO Ingreso a COMPR.AR Inicio Expediente...","og_url":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/","og_site_name":"OSEP Mendoza","article_publisher":"https:\/\/www.facebook.com\/OSEP.MendozaArg\/","article_modified_time":"2022-08-29T14:24:26+00:00","og_image":[{"url":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@OsepMza","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/","url":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/","name":"Proveedores - OSEP Mendoza","isPartOf":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/#primaryimage"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/#primaryimage"},"thumbnailUrl":"http:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg","datePublished":"2020-05-19T19:20:30+00:00","dateModified":"2022-08-29T14:24:26+00:00","breadcrumb":{"@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/#primaryimage","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/05\/proveedor.svg","width":66,"height":43},{"@type":"BreadcrumbList","@id":"https:\/\/osepmendoza.com.ar\/web\/proveedores-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/osepmendoza.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Proveedores"}]},{"@type":"WebSite","@id":"https:\/\/osepmendoza.com.ar\/web\/#website","url":"https:\/\/osepmendoza.com.ar\/web\/","name":"OSEP Mendoza","description":"Obra Social de los Empleados P\u00fablicos de Mendoza","publisher":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osepmendoza.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/osepmendoza.com.ar\/web\/#organization","name":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza","url":"https:\/\/osepmendoza.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","contentUrl":"https:\/\/osepmendoza.com.ar\/web\/wp-content\/uploads\/2020\/04\/lkTM9T9z.jpg","width":334,"height":334,"caption":"OSEP - Obra Social de Empleados P\u00fablicos de Mendoza"},"image":{"@id":"https:\/\/osepmendoza.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSEP.MendozaArg\/","https:\/\/x.com\/OsepMza","https:\/\/www.instagram.com\/osep.mendoza\/","https:\/\/www.youtube.com\/user\/osepvideos"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/pages\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":11,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/pages\/1253\/revisions"}],"predecessor-version":[{"id":46750,"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/pages\/1253\/revisions\/46750"}],"wp:attachment":[{"href":"https:\/\/osepmendoza.com.ar\/web\/wp-json\/wp\/v2\/media?parent=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}